{"id":191,"date":"2012-07-23T07:44:02","date_gmt":"2012-07-23T07:44:02","guid":{"rendered":"http:\/\/www.ridgi-pad.de\/blog\/?p=191"},"modified":"2018-12-18T11:00:31","modified_gmt":"2018-12-18T11:00:31","slug":"unsere-spende-an-der-richtigen-stelle","status":"publish","type":"post","link":"https:\/\/www.ridgi-pad.de\/blog\/unsere-spende-an-der-richtigen-stelle\/","title":{"rendered":"Unsere Spende an der richtigen Stelle"},"content":{"rendered":"<p><strong>Wir besuchen den Gnadenhof Lehnitz und hoffen mit unserer Spende helfen zu k\u00f6nnen<\/strong><\/p>\n<p>Grauer Himmel und es regnet in Str\u00f6men: Irgendwie passend. Bevor wir den Gnadenhof Lehnitz betreten haben, sp\u00fcrt man bei uns allen eine bedr\u00fcckte Stimmung. Wir kennen die Fotos des Hofes und wissen um die Schicksale der Tiere. Wenn Tiere den Gnadenhof Lehnitz erreichen, sind sie oft schwer verletzt, fast verhungert. Sie wurden ausgesetzt \u2013 allein gelassen. Als bekennende Tier- und Hundeliebhaber leiden wir mit. Aber wir sind da, um zu helfen.<\/p>\n<p>Offen und herzlich werden wir begr\u00fc\u00dft. Doch man merkt, die freiwilligen Helfer des Gnadenhofes sind verunsichert. Eine Frage liegt ihnen auf dem Herzen: \u201eUnd Ihr wollt uns einfach so Geld spenden? Warum?\u201c Berechtigte Frage: Wir wollen etwas Gutes tun \u2013 etwas von unserem wirtschaftlichen Erfolg zur\u00fcckgeben.<\/p>\n<p>Denn: Unseren Erfolg verdanken wir der Liebe und der Verantwortung unserer Kunden gegen\u00fcber ihren Hunden. Diese Verantwortung verk\u00f6rpern wir selbst und alle Beteiligten des Gnadenhofes wahrscheinlich noch viel mehr. Wir denken, es ist unsere Pflicht Projekte wie dieses, die Verantwortung \u00fcbernehmen und Tieren ein artgerechtes Leben erm\u00f6glichen, im Rahmen unserer M\u00f6glichkeiten zu unterst\u00fctzen.<\/p>\n<p><em>Andrea, ehrenamtliche Helferin und Pressesprecherin des Gnadenhofs, im Gespr\u00e4ch mit Stefan vom KV Shop<\/em><\/p>\n<h2>Wir \u00fcbernehmen Verantwortung<\/h2>\n<p>Gewohnt ist man eine solche Unterst\u00fctzung nicht, doch gebraucht wird das Geld dringend. \u201eEuer Geld ist wirklich ein Segen\u201c, sagt Andrea, ehrenamtliche Helferin und Pressesprecherin. Ihre Dankbarkeit ist sp\u00fcrbar und r\u00fchrt uns sehr, ist aber nicht unser Antrieb \u2013 den Tieren soll es besser gehen, Tieren wie Bob.<\/p>\n<p>Bob kommt auf uns zu und st\u00f6\u00dft uns an. Er zieht ein Rollgestell hinter sich her. Seine Hinterbeine sind gel\u00e4hmt. Bob sieht auf und sucht N\u00e4he \u2013 unsere N\u00e4he. Nacheinander gehen wir in die Knie und streicheln einen zufriedenen Hund. Doch Bobs Augen erz\u00e4hlen auch die andere Geschichte: Meine Familie hat mich alleine gelassen. Ich fiel meinem Herrchen vom Arm \u2013 und prallte mit einem harten Schlag auf den Boden. Danach ver\u00e4nderte sich alles. Ich konnte nicht mehr laufen. Keiner k\u00fcmmerte sich mehr um mich, keiner wollte mich mehr. Ich hatte Herrchen doch so lieb. Doch dann nahmen mich die Leute vom Gnadenhof Lehnitz bei sich auf. Seitdem ich hier bin, bin ich wieder richtig froh.<\/p>\n<h2>Den Tieren geht es in Lehnitz wirklich gut<\/h2>\n<p>Dank des Gnadenhofes Lehnitz kann Bob sein Leben wieder genie\u00dfen: er spielt, er tobt, er bekommt die Zuwendung, die er braucht und ist wieder, wie es sich f\u00fcr eine franz\u00f6sische Bulldoge geh\u00f6rt, ein frecher Kerl. Man kann ihn nur m\u00f6gen.<\/p>\n<p><em>Bob kann sich dank des Hunderollis auf dem Gel\u00e4nde des Gnadenhofs frei bewegen<\/em><br \/>\nUnsere anf\u00e4ngliche Sorge, das Leid der Tiere w\u00fcrde uns ersch\u00fcttern, ist vergangen. Den Tieren geht es richtig gut. Sie haben ein zu Hause gefunden und f\u00fchren ein lebenswertes und artgerechtes Leben. Es ist sch\u00f6n zu sehen, dass es ihnen trotz schwerem Schicksal gut geht. Liebesbed\u00fcrftig sind sie alle \u2013 oft genug wurden sie in ihrem Leben vernachl\u00e4ssigt. Die selbstlose und aufopfernde harte Arbeit von Sanny Schulz und Dana Grunert und allen ehrenamtlichen Helfern erm\u00f6glicht den Tieren ein artgerechtes und umsorgtes Leben.<\/p>\n<p>Im Gespr\u00e4ch tauschen wir unsere Erfahrungen der Hundehaltung aus, zeigen die Fotos unserer Hunde und berichten \u00fcber ihre liebgewonnenen Macken. Schnell ist die Problematik der Stra\u00dfenhunde Thema unserer Gespr\u00e4che. Bea, ehrenamtliche Helferin auf dem Gnadenhof Lehnitz, berichtet \u00fcber ihre Erfahrung in Rum\u00e4nien: \u201eIch kann viel ab, aber was ich in den rum\u00e4nische Bergen gesehen habe, trieb mir Tr\u00e4nen in die Augen. Das sind ganz schlimme Zust\u00e4nde, in denen Hunde dort leben.\u201c Der Gnadenhof Lehnitz kann einzelnen Hunden ein neues Leben schenken \u2013 nicht aber das gro\u00dfe Problem der Verantwortungslosigkeit l\u00f6sen. Wir sind hier nicht in Rum\u00e4nien oder Spanien, sondern in Berlin. Auch wenn der Gnadenhof Kleintiere aus dem Ausland aufnimmt, gibt es leider auch in Deutschland vermehrt das Problem der Verantwortungslosigkeit gegen\u00fcber Tieren.<\/p>\n<h2>Es gibt so viele traurige Geschichten zu erz\u00e4hlen<\/h2>\n<p>Wir k\u00f6nnten nun viele geh\u00f6rte Geschichten erz\u00e4hlen. Aber stellvertretend f\u00fcr so viele Schicksale, denen sich der Gnadenhof Lehnitz angenommen hat und stellvertretend f\u00fcr all die m\u00fchevolle Arbeit, die t\u00e4glich geleistet wird, soll die Geschichte von Promyk stehen.<\/p>\n<p>Nach einem Autounfall kam Promyk in ein polnisches Tierheim. Die Diagnose lautete Wirbels\u00e4ulen- und Beckenbruch. Er wurde operiert und erholte sich mit Hilfe einer Therapie. Das Tierheim stellte jedoch die Zahlungen f\u00fcr die Therapie ein. Im Januar 2011 fand Promyk Zuflucht im Gnadenhof Lehnitz. Die Aufnahme ist f\u00fcr jedes Tier die Lebensrettung. Sein Zustand war desolat: Der R\u00fcde konnte nicht alleine stehen, hatte dementsprechend wunde Stellen am Bein und war stark abgemagert.<\/p>\n<p>Solchen Tieren hilft der Gnadenhof: Die Tiere sollen hier nicht auf ihr Ende warten. Sie werden eben nicht aufgegeben und alleine ihrem Schicksal \u00fcberlassen. Sie werden versorgt. Die Tiere sollen das bestm\u00f6gliche und artgerechte Leben f\u00fchren, das sie mit ihrer Erkrankung oder Behinderung f\u00fchren k\u00f6nnen. Die Schritte hierzu gleichen sich immer wieder. Zun\u00e4chst gilt es herauszufinden, was passiert ist und worunter der Hund leidet. Das kl\u00e4rt immer der Gang zum Tierarzt. Promyk war ja bereits wieder auf dem Weg der Besserung. Nach kostspieligen Untersuchungen stand fest: Der eingesetzte Nagel zur Stabilisierung der Wirbels\u00e4ule sa\u00df nicht mehr an der richtigen Stelle und bereitete Promyk h\u00f6llische Schmerzen. Mehrere Operationen waren n\u00f6tig, die verdrehte und verkn\u00f6cherte Wirbels\u00e4ule wiederherzustellen. Diese dringend notwendigen Operationen konnten zum Gl\u00fcck durch Spendengelder finanziert werden. Mit Hilfe der \u00c4rzte und durch die liebevolle t\u00e4gliche Betreuung der Helfer des Gnadenhofes Lehnitz erholte sich Promyk. Dank Physiotherapie und Schwimmtraining der Tierheilpraktikerin Sanny Schulz, besteht berechtigte Hoffnung, dass sich Promyks Zustand weiter verbessert. Doch bereits jetzt konnte dem Hund ein neues Leben geschenkt werden. Dank des Hunderollis kann Promyk mit seinen Mitbewohnern auf dem Gel\u00e4nde des Gnadenhofs herumtollen und f\u00fchrt ein unbeschwertes Hundeleben.<\/p>\n<p><em>Stefan vom KV Shop und Tom von Ridgi Pad besuchen den Gnadenhof in Lehnitz<\/em><\/p>\n<h2>Die Tiere zu versorgen ist harte Arbeit<\/h2>\n<p>Der Gnadenhof Lehnitz rettet Tiere vor dem sicheren Tod. Er gibt zahlreichen Kleintieren Obhut und ein zu Hause. Derzeit m\u00fcssen dringende Umbauma\u00dfnahmen get\u00e4tigt werden. Auf dem Gel\u00e4nde m\u00fcssen Sturmsch\u00e4den behoben und der Wohnraum erneuert werden. Unsere Spenden flie\u00dfen direkt in den Bau einer Quarant\u00e4nestation. Diese ist besonders wichtig, um kranke Tiere behandeln zu k\u00f6nnen und die Ansteckungsgefahr f\u00fcr andere Bewohner auszuschlie\u00dfen. Die Versorgung der Tiere ist nicht nur harte Arbeit, sondern sie ist kostenintensiv. Die Tiere ben\u00f6tigen eine Voruntersuchung, um Gefahren f\u00fcr die anderen auszuschlie\u00dfen und um einen Heilungsplan erstellen zu k\u00f6nnen. Doch auch die laufenden Kosten m\u00fcssen gedeckt werden: Futter, Salben und Verbandsmittel, Medikamente, Windeln, Desinfektionsmittel, Einweghandschuhe etc.<\/p>\n<p>Einrichtungen, wie der Gnadenhof Lehnitz, sind oft die letzte M\u00f6glichkeit f\u00fcr Tiere ein beh\u00fctetes und artgerechtes Leben f\u00fchren zu k\u00f6nnen. Solche H\u00f6fe werden weder von staatlicher Seite noch durch eine pro bono Versorgung durch Tier\u00e4rzte unterst\u00fctzt. Sie sind ausschlie\u00dflich auf Spenden und der selbstlosen und aufopfernden Arbeit von freiwilligen Helfern angewiesen.<\/p>\n<h3>Wir hoffen mit unserer Spende ein wenig helfen zu k\u00f6nnen. Wir werden berichten.<\/h3>\n<p>&nbsp;<\/p>\n<div>\n<p>Ist ein Projekt von:<\/p>\n<div style=\"float: left; width: 200px; margin: 0 15px 0 0;\">\n<p>&nbsp;<\/p>\n<\/div>\n<div style=\"float: left; width: 200px; margin: 0 0px 0 0;\">\n<p><a href=\"https:\/\/www.ridgi-pad.de\/blog\/unser-tag-am-gnadenhof\/\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.kv-shop.de\/blog\/facebook\/newsletter\/logo_rp.jpg\" alt=\"Logo\" width=\"152\" height=\"81\" \/><\/a><\/p>\n<\/div>\n<p>&nbsp;<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Wir besuchen den Gnadenhof Lehnitz und hoffen mit unserer Spende helfen zu k\u00f6nnen Grauer Himmel und es regnet in Str\u00f6men: Irgendwie passend. Bevor wir den Gnadenhof Lehnitz betreten haben, sp\u00fcrt man bei uns allen eine bedr\u00fcckte Stimmung. Wir kennen die Fotos des Hofes und wissen um die Schicksale der Tiere. Wenn Tiere den Gnadenhof Lehnitz [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[87],"tags":[],"class_list":["post-191","post","type-post","status-publish","format-standard","hentry","category-ridgipad"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Wir besuchen den Gnadenhof Lehnitz und hoffen mit unserer Spende helfen zu k\u00f6nnen Grauer Himmel und es regnet in Str\u00f6men: Irgendwie passend. Bevor wir den Gnadenhof Lehnitz betreten haben, sp\u00fcrt man bei uns allen eine bedr\u00fcckte Stimmung. Wir kennen die Fotos des Hofes und wissen um die Schicksale der Tiere. Wenn Tiere den Gnadenhof Lehnitz\" \/>\n\t<meta name=\"robots\" content=\"max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n\t<meta name=\"author\" content=\"Tom von Ridgi-Pad\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.ridgi-pad.de\/blog\/unsere-spende-an-der-richtigen-stelle\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ridgi-pad.de\\\/blog\\\/unsere-spende-an-der-richtigen-stelle\\\/#article\",\"name\":\"Unsere Spende an der richtigen Stelle\",\"headline\":\"Unsere Spende an der richtigen Stelle\",\"author\":{\"@id\":\"https:\\\/\\\/www.ridgi-pad.de\\\/blog\\\/author\\\/tom-von-ridgi-pad\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.ridgi-pad.de\\\/blog\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.kv-shop.de\\\/blog\\\/facebook\\\/newsletter\\\/logo_rp.jpg\",\"@id\":\"https:\\\/\\\/www.ridgi-pad.de\\\/blog\\\/unsere-spende-an-der-richtigen-stelle\\\/#articleImage\"},\"datePublished\":\"2012-07-23T07:44:02+00:00\",\"dateModified\":\"2018-12-18T11:00:31+00:00\",\"inLanguage\":\"de-DE\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ridgi-pad.de\\\/blog\\\/unsere-spende-an-der-richtigen-stelle\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ridgi-pad.de\\\/blog\\\/unsere-spende-an-der-richtigen-stelle\\\/#webpage\"},\"articleSection\":\"RidgiPad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ridgi-pad.de\\\/blog\\\/unsere-spende-an-der-richtigen-stelle\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.ridgi-pad.de\\\/blog#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.ridgi-pad.de\\\/blog\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.ridgi-pad.de\\\/blog\\\/category\\\/ridgipad\\\/#listItem\",\"name\":\"RidgiPad\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.ridgi-pad.de\\\/blog\\\/category\\\/ridgipad\\\/#listItem\",\"position\":2,\"name\":\"RidgiPad\",\"item\":\"https:\\\/\\\/www.ridgi-pad.de\\\/blog\\\/category\\\/ridgipad\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.ridgi-pad.de\\\/blog\\\/unsere-spende-an-der-richtigen-stelle\\\/#listItem\",\"name\":\"Unsere Spende an der richtigen Stelle\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.ridgi-pad.de\\\/blog#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.ridgi-pad.de\\\/blog\\\/unsere-spende-an-der-richtigen-stelle\\\/#listItem\",\"position\":3,\"name\":\"Unsere Spende an der richtigen Stelle\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.ridgi-pad.de\\\/blog\\\/category\\\/ridgipad\\\/#listItem\",\"name\":\"RidgiPad\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ridgi-pad.de\\\/blog\\\/#organization\",\"name\":\"Ridgi Pad Blog\",\"url\":\"https:\\\/\\\/www.ridgi-pad.de\\\/blog\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ridgi-pad.de\\\/blog\\\/author\\\/tom-von-ridgi-pad\\\/#author\",\"url\":\"https:\\\/\\\/www.ridgi-pad.de\\\/blog\\\/author\\\/tom-von-ridgi-pad\\\/\",\"name\":\"Tom von Ridgi-Pad\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.ridgi-pad.de\\\/blog\\\/unsere-spende-an-der-richtigen-stelle\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2727a108203e27c8e0c976d5456ba70dba648f81ba4cb4d45ee76be3265fa7a3?s=96&r=g\",\"width\":96,\"height\":96,\"caption\":\"Tom von Ridgi-Pad\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ridgi-pad.de\\\/blog\\\/unsere-spende-an-der-richtigen-stelle\\\/#webpage\",\"url\":\"https:\\\/\\\/www.ridgi-pad.de\\\/blog\\\/unsere-spende-an-der-richtigen-stelle\\\/\",\"name\":\"Unsere Spende an der richtigen Stelle\",\"description\":\"Wir besuchen den Gnadenhof Lehnitz und hoffen mit unserer Spende helfen zu k\\u00f6nnen Grauer Himmel und es regnet in Str\\u00f6men: Irgendwie passend. Bevor wir den Gnadenhof Lehnitz betreten haben, sp\\u00fcrt man bei uns allen eine bedr\\u00fcckte Stimmung. Wir kennen die Fotos des Hofes und wissen um die Schicksale der Tiere. Wenn Tiere den Gnadenhof Lehnitz\",\"inLanguage\":\"de-DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ridgi-pad.de\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ridgi-pad.de\\\/blog\\\/unsere-spende-an-der-richtigen-stelle\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.ridgi-pad.de\\\/blog\\\/author\\\/tom-von-ridgi-pad\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.ridgi-pad.de\\\/blog\\\/author\\\/tom-von-ridgi-pad\\\/#author\"},\"datePublished\":\"2012-07-23T07:44:02+00:00\",\"dateModified\":\"2018-12-18T11:00:31+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ridgi-pad.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.ridgi-pad.de\\\/blog\\\/\",\"name\":\"Ridgi Pad Blog\",\"inLanguage\":\"de-DE\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ridgi-pad.de\\\/blog\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Unsere Spende an der richtigen Stelle","description":"Wir besuchen den Gnadenhof Lehnitz und hoffen mit unserer Spende helfen zu k\u00f6nnen Grauer Himmel und es regnet in Str\u00f6men: Irgendwie passend. Bevor wir den Gnadenhof Lehnitz betreten haben, sp\u00fcrt man bei uns allen eine bedr\u00fcckte Stimmung. Wir kennen die Fotos des Hofes und wissen um die Schicksale der Tiere. Wenn Tiere den Gnadenhof Lehnitz","canonical_url":"https:\/\/www.ridgi-pad.de\/blog\/unsere-spende-an-der-richtigen-stelle\/","robots":"max-snippet:-1, max-image-preview:large, max-video-preview:-1","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ridgi-pad.de\/blog\/unsere-spende-an-der-richtigen-stelle\/#article","name":"Unsere Spende an der richtigen Stelle","headline":"Unsere Spende an der richtigen Stelle","author":{"@id":"https:\/\/www.ridgi-pad.de\/blog\/author\/tom-von-ridgi-pad\/#author"},"publisher":{"@id":"https:\/\/www.ridgi-pad.de\/blog\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.kv-shop.de\/blog\/facebook\/newsletter\/logo_rp.jpg","@id":"https:\/\/www.ridgi-pad.de\/blog\/unsere-spende-an-der-richtigen-stelle\/#articleImage"},"datePublished":"2012-07-23T07:44:02+00:00","dateModified":"2018-12-18T11:00:31+00:00","inLanguage":"de-DE","mainEntityOfPage":{"@id":"https:\/\/www.ridgi-pad.de\/blog\/unsere-spende-an-der-richtigen-stelle\/#webpage"},"isPartOf":{"@id":"https:\/\/www.ridgi-pad.de\/blog\/unsere-spende-an-der-richtigen-stelle\/#webpage"},"articleSection":"RidgiPad"},{"@type":"BreadcrumbList","@id":"https:\/\/www.ridgi-pad.de\/blog\/unsere-spende-an-der-richtigen-stelle\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.ridgi-pad.de\/blog#listItem","position":1,"name":"Home","item":"https:\/\/www.ridgi-pad.de\/blog","nextItem":{"@type":"ListItem","@id":"https:\/\/www.ridgi-pad.de\/blog\/category\/ridgipad\/#listItem","name":"RidgiPad"}},{"@type":"ListItem","@id":"https:\/\/www.ridgi-pad.de\/blog\/category\/ridgipad\/#listItem","position":2,"name":"RidgiPad","item":"https:\/\/www.ridgi-pad.de\/blog\/category\/ridgipad\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.ridgi-pad.de\/blog\/unsere-spende-an-der-richtigen-stelle\/#listItem","name":"Unsere Spende an der richtigen Stelle"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.ridgi-pad.de\/blog#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.ridgi-pad.de\/blog\/unsere-spende-an-der-richtigen-stelle\/#listItem","position":3,"name":"Unsere Spende an der richtigen Stelle","previousItem":{"@type":"ListItem","@id":"https:\/\/www.ridgi-pad.de\/blog\/category\/ridgipad\/#listItem","name":"RidgiPad"}}]},{"@type":"Organization","@id":"https:\/\/www.ridgi-pad.de\/blog\/#organization","name":"Ridgi Pad Blog","url":"https:\/\/www.ridgi-pad.de\/blog\/"},{"@type":"Person","@id":"https:\/\/www.ridgi-pad.de\/blog\/author\/tom-von-ridgi-pad\/#author","url":"https:\/\/www.ridgi-pad.de\/blog\/author\/tom-von-ridgi-pad\/","name":"Tom von Ridgi-Pad","image":{"@type":"ImageObject","@id":"https:\/\/www.ridgi-pad.de\/blog\/unsere-spende-an-der-richtigen-stelle\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/2727a108203e27c8e0c976d5456ba70dba648f81ba4cb4d45ee76be3265fa7a3?s=96&r=g","width":96,"height":96,"caption":"Tom von Ridgi-Pad"}},{"@type":"WebPage","@id":"https:\/\/www.ridgi-pad.de\/blog\/unsere-spende-an-der-richtigen-stelle\/#webpage","url":"https:\/\/www.ridgi-pad.de\/blog\/unsere-spende-an-der-richtigen-stelle\/","name":"Unsere Spende an der richtigen Stelle","description":"Wir besuchen den Gnadenhof Lehnitz und hoffen mit unserer Spende helfen zu k\u00f6nnen Grauer Himmel und es regnet in Str\u00f6men: Irgendwie passend. Bevor wir den Gnadenhof Lehnitz betreten haben, sp\u00fcrt man bei uns allen eine bedr\u00fcckte Stimmung. Wir kennen die Fotos des Hofes und wissen um die Schicksale der Tiere. Wenn Tiere den Gnadenhof Lehnitz","inLanguage":"de-DE","isPartOf":{"@id":"https:\/\/www.ridgi-pad.de\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.ridgi-pad.de\/blog\/unsere-spende-an-der-richtigen-stelle\/#breadcrumblist"},"author":{"@id":"https:\/\/www.ridgi-pad.de\/blog\/author\/tom-von-ridgi-pad\/#author"},"creator":{"@id":"https:\/\/www.ridgi-pad.de\/blog\/author\/tom-von-ridgi-pad\/#author"},"datePublished":"2012-07-23T07:44:02+00:00","dateModified":"2018-12-18T11:00:31+00:00"},{"@type":"WebSite","@id":"https:\/\/www.ridgi-pad.de\/blog\/#website","url":"https:\/\/www.ridgi-pad.de\/blog\/","name":"Ridgi Pad Blog","inLanguage":"de-DE","publisher":{"@id":"https:\/\/www.ridgi-pad.de\/blog\/#organization"}}]}},"aioseo_meta_data":{"post_id":"191","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2020-12-24 19:18:49","updated":"2025-06-04 22:49:29","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.ridgi-pad.de\/blog\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.ridgi-pad.de\/blog\/category\/ridgipad\/\" title=\"RidgiPad\">RidgiPad<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tUnsere Spende an der richtigen Stelle\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.ridgi-pad.de\/blog"},{"label":"RidgiPad","link":"https:\/\/www.ridgi-pad.de\/blog\/category\/ridgipad\/"},{"label":"Unsere Spende an der richtigen Stelle","link":"https:\/\/www.ridgi-pad.de\/blog\/unsere-spende-an-der-richtigen-stelle\/"}],"_links":{"self":[{"href":"https:\/\/www.ridgi-pad.de\/blog\/wp-json\/wp\/v2\/posts\/191","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ridgi-pad.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ridgi-pad.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ridgi-pad.de\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ridgi-pad.de\/blog\/wp-json\/wp\/v2\/comments?post=191"}],"version-history":[{"count":31,"href":"https:\/\/www.ridgi-pad.de\/blog\/wp-json\/wp\/v2\/posts\/191\/revisions"}],"predecessor-version":[{"id":703,"href":"https:\/\/www.ridgi-pad.de\/blog\/wp-json\/wp\/v2\/posts\/191\/revisions\/703"}],"wp:attachment":[{"href":"https:\/\/www.ridgi-pad.de\/blog\/wp-json\/wp\/v2\/media?parent=191"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ridgi-pad.de\/blog\/wp-json\/wp\/v2\/categories?post=191"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ridgi-pad.de\/blog\/wp-json\/wp\/v2\/tags?post=191"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}