{"id":843,"date":"2019-03-07T09:11:45","date_gmt":"2019-03-07T09:11:45","guid":{"rendered":"https:\/\/www.ridgi-pad.de\/blog\/?p=843"},"modified":"2019-08-28T13:15:42","modified_gmt":"2019-08-28T13:15:42","slug":"sport-mit-dem-hund-wie-sie-sich-und-ihrem-vierbeiner-etwas-gutes-tun","status":"publish","type":"post","link":"https:\/\/www.ridgi-pad.de\/blog\/sport-mit-dem-hund-wie-sie-sich-und-ihrem-vierbeiner-etwas-gutes-tun\/","title":{"rendered":"Sport mit dem Hund: Wie Sie sich und Ihrem Vierbeiner etwas Gutes tun"},"content":{"rendered":"\n<p><strong>Sie\nwollen nach der Arbeit noch schnell zum Sport, doch halt: Ihr Hund verlangt\nnach der allabendlichen Gassi-Runde, die man ihm nat\u00fcrlich nicht verwehren\nkann. Wenn Sie glauben, Ihre sportliche Bet\u00e4tigung jetzt hintenanstellen zu\nm\u00fcssen, haben wir eine einfache wie effektive L\u00f6sung: Kombinieren Sie Hund und\nSport! Wir zeigen Ihnen, wie es geht. <\/strong><\/p>\n\n\n\n<p>Ein\npaar Infos, bevor es losgeht: F\u00fchren Sie den Hund langsam an jede besondere\nForm der Bewegung heran. Fangen Sie klein an und erh\u00f6hen Sie die Belastung dann\npeu \u00e0 peu. Mit der Zeit k\u00f6nnen das Tempo und die zur\u00fcckgelegten Entfernungen\ngesteigert werden. Allerdings sind das Alter und der Gesundheitszustand des\nTieres unbedingt zu beachten. Zum Joggen sollten Sie den Hund erst mitnehmen,\nwenn er ein, zwei Jahre alt und ausgewachsen ist. Denn Welpen und\nheranwachsende Hunde besitzen noch keine vollst\u00e4ndig ausgebildete Sehnen und\nB\u00e4nder. L\u00e4ngere Strecken im Dauerlauf sind f\u00fcr sie deswegen noch tabu. Doch\nnicht jeder Vierbeiner hat Spa\u00df an einer Joggingrunde.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Sport,\nFitness und Spa\u00df: 3 Varianten f\u00fcr Hund und Herrchen<\/strong><\/h2>\n\n\n\n<p>Es\ngibt verschiedene M\u00f6glichkeiten, wie Sie sportliche Bet\u00e4tigung und Gassi gehen\nunter einen Hut bringen: <\/p>\n\n\n\n<p>Beim\nAgility geht es in erster Linie um den Hund. Der Vierbeiner absolviert einen\nHindernislauf, bei dem Geschwindigkeit, Beweglichkeit, Balance und Sprungkraft\ngefragt sind. Dem Herrchen kommt die Rolle des Trainers und Motivators zu.\nJedoch ist auch er\/sie sportlich gefordert. Man muss seinen Liebling von\nStation zu Station begleiten, um immer auf der H\u00f6he zu sein und ihn anzufeuern.\n<\/p>\n\n\n\n<p>F\u00fcr\nAmbitonierte empfiehlt sich das Canicross. Hier geht es mit dem Hund durchs\nGel\u00e4nde. Zwar sind Mensch und Hund wie \u00fcblich durch eine Leine verbunden, doch\nes gibt einen bedeutenden Unterschied zum normalen Prozedere \u2013 der Hund\n\u00fcbernimmt die F\u00fchrung und der Mensch folgt. Deshalb ist die zwei Meter lange\nLeine besonders flexibel, verf\u00fcgt \u00fcber einen Ruckd\u00e4mpfer und hat auch einen\nNotfallhaken. Denn die Vierbeiner sind in der Regel deutlich schneller\nunterwegs, weshalb ein schnelles L\u00f6sen der Leine in bestimmten Situationen\nwichtig sein kann. Sind alle Vorkehrungen getroffen, geht es durch Felder, Wald\nund Wiesen. Hund und Mensch sollten komplett gesund und sportlich fit sein. Die\nZugkraft des Tieres sorgt f\u00fcr erh\u00f6htes Tempo. Das Duo erreicht\nGeschwindigkeiten von bis zu 30 km\/h. Wer Herausforderungen mag und sich vorab\ngut informiert, findet mit dem Canicross vielleicht eine neue\nLieblingsbesch\u00e4ftigung.&nbsp;&nbsp; <\/p>\n\n\n\n<p>Aus\nden USA stammt der Trend des Dogdance. Dabei wird eine Choreographie aus\nKunstst\u00fcckchen und Bewegungsabl\u00e4ufen einge\u00fcbt, die einem Tanz gleicht. Da darf\nMusik nat\u00fcrlich nicht fehlen. Zun\u00e4chst werden die einzelnen Elemente trainiert,\num sie sp\u00e4ter zu&nbsp; einer fl\u00fcssigen Abfolge\nzusammenzusetzen. Aus Pf\u00f6tchengeben, Rolle, Totstellen, Slalom, Spr\u00fcnge und\nvielem mehr entsteht eine kreative wie unterhaltsame Sequenz. Hier sind der\nFantasie keine Grenzen gesetzt. Nebenbei verbindet man Spa\u00df und Unterhaltung\nmit Lernerfolgen. Wenn die Choreo sitzt, kann zur passenden Musik getanzt\nwerden. Diese Sportart f\u00fcr Mensch und Hund hat sogar Turniere samt Preisen zu\nbieten.&nbsp; <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sie wollen nach der Arbeit noch schnell zum Sport, doch halt: Ihr Hund verlangt nach der allabendlichen Gassi-Runde, die man ihm nat\u00fcrlich nicht verwehren kann. Wenn Sie glauben, Ihre sportliche Bet\u00e4tigung jetzt hintenanstellen zu m\u00fcssen, haben wir eine einfache wie effektive L\u00f6sung: Kombinieren Sie Hund und Sport! Wir zeigen Ihnen, wie es geht. Ein paar [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":947,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-843","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Hund und Sport: Das ist die ideale Kombination, die nicht nur Hund, sondern auch Herrchen Spa\u00df macht. Wir zeigen, wie es geht.\" \/>\n\t<meta name=\"robots\" content=\"max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n\t<meta name=\"author\" content=\"Tom von Ridgi-Pad\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.ridgi-pad.de\/blog\/sport-mit-dem-hund-wie-sie-sich-und-ihrem-vierbeiner-etwas-gutes-tun\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ridgi-pad.de\\\/blog\\\/sport-mit-dem-hund-wie-sie-sich-und-ihrem-vierbeiner-etwas-gutes-tun\\\/#article\",\"name\":\"Sport mit dem Hund: Wie Sie dem Hund etwas Gutes tun\",\"headline\":\"Sport mit dem Hund: Wie Sie sich und Ihrem Vierbeiner etwas Gutes tun\",\"author\":{\"@id\":\"https:\\\/\\\/www.ridgi-pad.de\\\/blog\\\/author\\\/tom-von-ridgi-pad\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.ridgi-pad.de\\\/blog\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.ridgi-pad.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/sport-mit-hund.jpg\",\"width\":2583,\"height\":1964,\"caption\":\"&copy; pixabay  - pexels.com\"},\"datePublished\":\"2019-03-07T09:11:45+00:00\",\"dateModified\":\"2019-08-28T13:15:42+00:00\",\"inLanguage\":\"de-DE\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ridgi-pad.de\\\/blog\\\/sport-mit-dem-hund-wie-sie-sich-und-ihrem-vierbeiner-etwas-gutes-tun\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ridgi-pad.de\\\/blog\\\/sport-mit-dem-hund-wie-sie-sich-und-ihrem-vierbeiner-etwas-gutes-tun\\\/#webpage\"},\"articleSection\":\"Allgemein\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ridgi-pad.de\\\/blog\\\/sport-mit-dem-hund-wie-sie-sich-und-ihrem-vierbeiner-etwas-gutes-tun\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.ridgi-pad.de\\\/blog#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.ridgi-pad.de\\\/blog\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.ridgi-pad.de\\\/blog\\\/category\\\/allgemein\\\/#listItem\",\"name\":\"Allgemein\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.ridgi-pad.de\\\/blog\\\/category\\\/allgemein\\\/#listItem\",\"position\":2,\"name\":\"Allgemein\",\"item\":\"https:\\\/\\\/www.ridgi-pad.de\\\/blog\\\/category\\\/allgemein\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.ridgi-pad.de\\\/blog\\\/sport-mit-dem-hund-wie-sie-sich-und-ihrem-vierbeiner-etwas-gutes-tun\\\/#listItem\",\"name\":\"Sport mit dem Hund: Wie Sie sich und Ihrem Vierbeiner etwas Gutes tun\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.ridgi-pad.de\\\/blog#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.ridgi-pad.de\\\/blog\\\/sport-mit-dem-hund-wie-sie-sich-und-ihrem-vierbeiner-etwas-gutes-tun\\\/#listItem\",\"position\":3,\"name\":\"Sport mit dem Hund: Wie Sie sich und Ihrem Vierbeiner etwas Gutes tun\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.ridgi-pad.de\\\/blog\\\/category\\\/allgemein\\\/#listItem\",\"name\":\"Allgemein\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ridgi-pad.de\\\/blog\\\/#organization\",\"name\":\"Ridgi Pad Blog\",\"url\":\"https:\\\/\\\/www.ridgi-pad.de\\\/blog\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ridgi-pad.de\\\/blog\\\/author\\\/tom-von-ridgi-pad\\\/#author\",\"url\":\"https:\\\/\\\/www.ridgi-pad.de\\\/blog\\\/author\\\/tom-von-ridgi-pad\\\/\",\"name\":\"Tom von Ridgi-Pad\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.ridgi-pad.de\\\/blog\\\/sport-mit-dem-hund-wie-sie-sich-und-ihrem-vierbeiner-etwas-gutes-tun\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2727a108203e27c8e0c976d5456ba70dba648f81ba4cb4d45ee76be3265fa7a3?s=96&r=g\",\"width\":96,\"height\":96,\"caption\":\"Tom von Ridgi-Pad\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ridgi-pad.de\\\/blog\\\/sport-mit-dem-hund-wie-sie-sich-und-ihrem-vierbeiner-etwas-gutes-tun\\\/#webpage\",\"url\":\"https:\\\/\\\/www.ridgi-pad.de\\\/blog\\\/sport-mit-dem-hund-wie-sie-sich-und-ihrem-vierbeiner-etwas-gutes-tun\\\/\",\"name\":\"Sport mit dem Hund: Wie Sie dem Hund etwas Gutes tun\",\"description\":\"Hund und Sport: Das ist die ideale Kombination, die nicht nur Hund, sondern auch Herrchen Spa\\u00df macht. Wir zeigen, wie es geht.\",\"inLanguage\":\"de-DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ridgi-pad.de\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ridgi-pad.de\\\/blog\\\/sport-mit-dem-hund-wie-sie-sich-und-ihrem-vierbeiner-etwas-gutes-tun\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.ridgi-pad.de\\\/blog\\\/author\\\/tom-von-ridgi-pad\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.ridgi-pad.de\\\/blog\\\/author\\\/tom-von-ridgi-pad\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.ridgi-pad.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/sport-mit-hund.jpg\",\"@id\":\"https:\\\/\\\/www.ridgi-pad.de\\\/blog\\\/sport-mit-dem-hund-wie-sie-sich-und-ihrem-vierbeiner-etwas-gutes-tun\\\/#mainImage\",\"width\":2583,\"height\":1964,\"caption\":\"&copy; pixabay  - pexels.com\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ridgi-pad.de\\\/blog\\\/sport-mit-dem-hund-wie-sie-sich-und-ihrem-vierbeiner-etwas-gutes-tun\\\/#mainImage\"},\"datePublished\":\"2019-03-07T09:11:45+00:00\",\"dateModified\":\"2019-08-28T13:15:42+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ridgi-pad.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.ridgi-pad.de\\\/blog\\\/\",\"name\":\"Ridgi Pad Blog\",\"inLanguage\":\"de-DE\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ridgi-pad.de\\\/blog\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Sport mit dem Hund: Wie Sie dem Hund etwas Gutes tun","description":"Hund und Sport: Das ist die ideale Kombination, die nicht nur Hund, sondern auch Herrchen Spa\u00df macht. Wir zeigen, wie es geht.","canonical_url":"https:\/\/www.ridgi-pad.de\/blog\/sport-mit-dem-hund-wie-sie-sich-und-ihrem-vierbeiner-etwas-gutes-tun\/","robots":"max-snippet:-1, max-image-preview:large, max-video-preview:-1","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ridgi-pad.de\/blog\/sport-mit-dem-hund-wie-sie-sich-und-ihrem-vierbeiner-etwas-gutes-tun\/#article","name":"Sport mit dem Hund: Wie Sie dem Hund etwas Gutes tun","headline":"Sport mit dem Hund: Wie Sie sich und Ihrem Vierbeiner etwas Gutes tun","author":{"@id":"https:\/\/www.ridgi-pad.de\/blog\/author\/tom-von-ridgi-pad\/#author"},"publisher":{"@id":"https:\/\/www.ridgi-pad.de\/blog\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.ridgi-pad.de\/blog\/wp-content\/uploads\/2019\/03\/sport-mit-hund.jpg","width":2583,"height":1964,"caption":"&copy; pixabay  - pexels.com"},"datePublished":"2019-03-07T09:11:45+00:00","dateModified":"2019-08-28T13:15:42+00:00","inLanguage":"de-DE","mainEntityOfPage":{"@id":"https:\/\/www.ridgi-pad.de\/blog\/sport-mit-dem-hund-wie-sie-sich-und-ihrem-vierbeiner-etwas-gutes-tun\/#webpage"},"isPartOf":{"@id":"https:\/\/www.ridgi-pad.de\/blog\/sport-mit-dem-hund-wie-sie-sich-und-ihrem-vierbeiner-etwas-gutes-tun\/#webpage"},"articleSection":"Allgemein"},{"@type":"BreadcrumbList","@id":"https:\/\/www.ridgi-pad.de\/blog\/sport-mit-dem-hund-wie-sie-sich-und-ihrem-vierbeiner-etwas-gutes-tun\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.ridgi-pad.de\/blog#listItem","position":1,"name":"Home","item":"https:\/\/www.ridgi-pad.de\/blog","nextItem":{"@type":"ListItem","@id":"https:\/\/www.ridgi-pad.de\/blog\/category\/allgemein\/#listItem","name":"Allgemein"}},{"@type":"ListItem","@id":"https:\/\/www.ridgi-pad.de\/blog\/category\/allgemein\/#listItem","position":2,"name":"Allgemein","item":"https:\/\/www.ridgi-pad.de\/blog\/category\/allgemein\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.ridgi-pad.de\/blog\/sport-mit-dem-hund-wie-sie-sich-und-ihrem-vierbeiner-etwas-gutes-tun\/#listItem","name":"Sport mit dem Hund: Wie Sie sich und Ihrem Vierbeiner etwas Gutes tun"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.ridgi-pad.de\/blog#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.ridgi-pad.de\/blog\/sport-mit-dem-hund-wie-sie-sich-und-ihrem-vierbeiner-etwas-gutes-tun\/#listItem","position":3,"name":"Sport mit dem Hund: Wie Sie sich und Ihrem Vierbeiner etwas Gutes tun","previousItem":{"@type":"ListItem","@id":"https:\/\/www.ridgi-pad.de\/blog\/category\/allgemein\/#listItem","name":"Allgemein"}}]},{"@type":"Organization","@id":"https:\/\/www.ridgi-pad.de\/blog\/#organization","name":"Ridgi Pad Blog","url":"https:\/\/www.ridgi-pad.de\/blog\/"},{"@type":"Person","@id":"https:\/\/www.ridgi-pad.de\/blog\/author\/tom-von-ridgi-pad\/#author","url":"https:\/\/www.ridgi-pad.de\/blog\/author\/tom-von-ridgi-pad\/","name":"Tom von Ridgi-Pad","image":{"@type":"ImageObject","@id":"https:\/\/www.ridgi-pad.de\/blog\/sport-mit-dem-hund-wie-sie-sich-und-ihrem-vierbeiner-etwas-gutes-tun\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/2727a108203e27c8e0c976d5456ba70dba648f81ba4cb4d45ee76be3265fa7a3?s=96&r=g","width":96,"height":96,"caption":"Tom von Ridgi-Pad"}},{"@type":"WebPage","@id":"https:\/\/www.ridgi-pad.de\/blog\/sport-mit-dem-hund-wie-sie-sich-und-ihrem-vierbeiner-etwas-gutes-tun\/#webpage","url":"https:\/\/www.ridgi-pad.de\/blog\/sport-mit-dem-hund-wie-sie-sich-und-ihrem-vierbeiner-etwas-gutes-tun\/","name":"Sport mit dem Hund: Wie Sie dem Hund etwas Gutes tun","description":"Hund und Sport: Das ist die ideale Kombination, die nicht nur Hund, sondern auch Herrchen Spa\u00df macht. Wir zeigen, wie es geht.","inLanguage":"de-DE","isPartOf":{"@id":"https:\/\/www.ridgi-pad.de\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.ridgi-pad.de\/blog\/sport-mit-dem-hund-wie-sie-sich-und-ihrem-vierbeiner-etwas-gutes-tun\/#breadcrumblist"},"author":{"@id":"https:\/\/www.ridgi-pad.de\/blog\/author\/tom-von-ridgi-pad\/#author"},"creator":{"@id":"https:\/\/www.ridgi-pad.de\/blog\/author\/tom-von-ridgi-pad\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/www.ridgi-pad.de\/blog\/wp-content\/uploads\/2019\/03\/sport-mit-hund.jpg","@id":"https:\/\/www.ridgi-pad.de\/blog\/sport-mit-dem-hund-wie-sie-sich-und-ihrem-vierbeiner-etwas-gutes-tun\/#mainImage","width":2583,"height":1964,"caption":"&copy; pixabay  - pexels.com"},"primaryImageOfPage":{"@id":"https:\/\/www.ridgi-pad.de\/blog\/sport-mit-dem-hund-wie-sie-sich-und-ihrem-vierbeiner-etwas-gutes-tun\/#mainImage"},"datePublished":"2019-03-07T09:11:45+00:00","dateModified":"2019-08-28T13:15:42+00:00"},{"@type":"WebSite","@id":"https:\/\/www.ridgi-pad.de\/blog\/#website","url":"https:\/\/www.ridgi-pad.de\/blog\/","name":"Ridgi Pad Blog","inLanguage":"de-DE","publisher":{"@id":"https:\/\/www.ridgi-pad.de\/blog\/#organization"}}]}},"aioseo_meta_data":{"post_id":"843","title":"Sport mit dem Hund: Wie Sie dem Hund etwas Gutes tun","description":"Hund und Sport: Das ist die ideale Kombination, die nicht nur Hund, sondern auch Herrchen Spa\u00df macht. Wir zeigen, wie es geht.","keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2020-12-24 19:18:49","updated":"2025-06-04 22:53:29","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.ridgi-pad.de\/blog\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.ridgi-pad.de\/blog\/category\/allgemein\/\" title=\"Allgemein\">Allgemein<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tSport mit dem Hund: Wie Sie sich und Ihrem Vierbeiner etwas Gutes tun\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.ridgi-pad.de\/blog"},{"label":"Allgemein","link":"https:\/\/www.ridgi-pad.de\/blog\/category\/allgemein\/"},{"label":"Sport mit dem Hund: Wie Sie sich und Ihrem Vierbeiner etwas Gutes tun","link":"https:\/\/www.ridgi-pad.de\/blog\/sport-mit-dem-hund-wie-sie-sich-und-ihrem-vierbeiner-etwas-gutes-tun\/"}],"_links":{"self":[{"href":"https:\/\/www.ridgi-pad.de\/blog\/wp-json\/wp\/v2\/posts\/843","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ridgi-pad.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ridgi-pad.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ridgi-pad.de\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ridgi-pad.de\/blog\/wp-json\/wp\/v2\/comments?post=843"}],"version-history":[{"count":2,"href":"https:\/\/www.ridgi-pad.de\/blog\/wp-json\/wp\/v2\/posts\/843\/revisions"}],"predecessor-version":[{"id":949,"href":"https:\/\/www.ridgi-pad.de\/blog\/wp-json\/wp\/v2\/posts\/843\/revisions\/949"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ridgi-pad.de\/blog\/wp-json\/wp\/v2\/media\/947"}],"wp:attachment":[{"href":"https:\/\/www.ridgi-pad.de\/blog\/wp-json\/wp\/v2\/media?parent=843"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ridgi-pad.de\/blog\/wp-json\/wp\/v2\/categories?post=843"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ridgi-pad.de\/blog\/wp-json\/wp\/v2\/tags?post=843"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}